{"id":57500,"date":"2021-09-27T11:40:57","date_gmt":"2021-09-27T09:40:57","guid":{"rendered":"http:\/\/topa.be\/glossary\/actes-des-apotres\/"},"modified":"2021-09-27T11:40:57","modified_gmt":"2021-09-27T09:40:57","slug":"actes-des-apotres","status":"publish","type":"glossary","link":"https:\/\/topa.be\/fr\/glossary\/actes-des-apotres\/","title":{"rendered":"Actes des Ap\u00f4tres"},"content":{"rendered":"<p style=\"text-align: justify;\">Livre du Nouveau Testament que l&rsquo;\u00e9vang\u00e9liste Luc a \u00e9crit comme une suite \u00e0 son \u00c9vangile. Il y d\u00e9crit les d\u00e9buts de la jeune \u00c9glise apr\u00e8s la mort de J\u00e9sus, avec Pierre et Paul comme figures centrales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Livre du Nouveau Testament que l&rsquo;\u00e9vang\u00e9liste Luc a \u00e9crit comme une suite \u00e0 son \u00c9vangile. Il y d\u00e9crit les d\u00e9buts de la jeune \u00c9glise apr\u00e8s la mort de J\u00e9sus, avec Pierre et Paul comme figures centrales.<\/p>\n","protected":false},"author":16,"featured_media":0,"parent":0,"template":"","glossary-cat":[148],"class_list":["post-57500","glossary","type-glossary","status-publish","hentry","glossary-cat-la-foi"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"noindex, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"Marc Dehaese\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/topa.be\/fr\/glossary\/actes-des-apotres\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"TOPA | Antwerpen, Kerken en ToerismeToerismepastoraal, Bisdom Antwerpen (TOPA vzw)\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Actes des Ap\u00f4tres | TOPA\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/topa.be\/fr\/glossary\/actes-des-apotres\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-09-27T09:40:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-09-27T09:40:57+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Actes des Ap\u00f4tres | TOPA\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/glossary\\\/actes-des-apotres\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/topa.be\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/glossary\\\/#listItem\",\"name\":\"Glossary Terms\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/glossary\\\/#listItem\",\"position\":2,\"name\":\"Glossary Terms\",\"item\":\"https:\\\/\\\/topa.be\\\/fr\\\/glossary\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/glossary-cat\\\/la-foi\\\/#listItem\",\"name\":\"La foi\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/glossary-cat\\\/la-foi\\\/#listItem\",\"position\":3,\"name\":\"La foi\",\"item\":\"https:\\\/\\\/topa.be\\\/fr\\\/glossary-cat\\\/la-foi\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/glossary\\\/actes-des-apotres\\\/#listItem\",\"name\":\"Actes des Ap\\u00f4tres\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/glossary\\\/#listItem\",\"name\":\"Glossary Terms\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/glossary\\\/actes-des-apotres\\\/#listItem\",\"position\":4,\"name\":\"Actes des Ap\\u00f4tres\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/glossary-cat\\\/la-foi\\\/#listItem\",\"name\":\"La foi\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/#organization\",\"name\":\"TOPA vzw - Antwerpen\",\"description\":\"Antwerpen, Kerken en ToerismeToerismepastoraal, Bisdom Antwerpen (TOPA vzw)\",\"url\":\"https:\\\/\\\/topa.be\\\/fr\\\/\",\"email\":\"info@topa.be\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/topa.be\\\/wp-content\\\/uploads\\\/cropped-logo_splash.jpg\",\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/glossary\\\/actes-des-apotres\\\/#organizationLogo\",\"width\":200,\"height\":200},\"image\":{\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/glossary\\\/actes-des-apotres\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/author\\\/topa\\\/#author\",\"url\":\"https:\\\/\\\/topa.be\\\/fr\\\/author\\\/topa\\\/\",\"name\":\"Marc Dehaese\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/glossary\\\/actes-des-apotres\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ce0c55c105036574ca271bbee95fc95bcec1e19cb865a85257048c44ee054cb9?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Marc Dehaese\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/glossary\\\/actes-des-apotres\\\/#webpage\",\"url\":\"https:\\\/\\\/topa.be\\\/fr\\\/glossary\\\/actes-des-apotres\\\/\",\"name\":\"Actes des Ap\\u00f4tres | TOPA\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/glossary\\\/actes-des-apotres\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/author\\\/topa\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/author\\\/topa\\\/#author\"},\"datePublished\":\"2021-09-27T11:40:57+02:00\",\"dateModified\":\"2021-09-27T11:40:57+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/topa.be\\\/fr\\\/\",\"name\":\"TOPA\",\"description\":\"Antwerpen, Kerken en ToerismeToerismepastoraal, Bisdom Antwerpen (TOPA vzw)\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/topa.be\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Actes des Ap\u00f4tres | TOPA","description":"","canonical_url":"https:\/\/topa.be\/fr\/glossary\/actes-des-apotres\/","robots":"noindex, max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/topa.be\/fr\/glossary\/actes-des-apotres\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/topa.be\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/topa.be\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/topa.be\/fr\/glossary\/#listItem","name":"Glossary Terms"}},{"@type":"ListItem","@id":"https:\/\/topa.be\/fr\/glossary\/#listItem","position":2,"name":"Glossary Terms","item":"https:\/\/topa.be\/fr\/glossary\/","nextItem":{"@type":"ListItem","@id":"https:\/\/topa.be\/fr\/glossary-cat\/la-foi\/#listItem","name":"La foi"},"previousItem":{"@type":"ListItem","@id":"https:\/\/topa.be\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/topa.be\/fr\/glossary-cat\/la-foi\/#listItem","position":3,"name":"La foi","item":"https:\/\/topa.be\/fr\/glossary-cat\/la-foi\/","nextItem":{"@type":"ListItem","@id":"https:\/\/topa.be\/fr\/glossary\/actes-des-apotres\/#listItem","name":"Actes des Ap\u00f4tres"},"previousItem":{"@type":"ListItem","@id":"https:\/\/topa.be\/fr\/glossary\/#listItem","name":"Glossary Terms"}},{"@type":"ListItem","@id":"https:\/\/topa.be\/fr\/glossary\/actes-des-apotres\/#listItem","position":4,"name":"Actes des Ap\u00f4tres","previousItem":{"@type":"ListItem","@id":"https:\/\/topa.be\/fr\/glossary-cat\/la-foi\/#listItem","name":"La foi"}}]},{"@type":"Organization","@id":"https:\/\/topa.be\/fr\/#organization","name":"TOPA vzw - Antwerpen","description":"Antwerpen, Kerken en ToerismeToerismepastoraal, Bisdom Antwerpen (TOPA vzw)","url":"https:\/\/topa.be\/fr\/","email":"info@topa.be","logo":{"@type":"ImageObject","url":"https:\/\/topa.be\/wp-content\/uploads\/cropped-logo_splash.jpg","@id":"https:\/\/topa.be\/fr\/glossary\/actes-des-apotres\/#organizationLogo","width":200,"height":200},"image":{"@id":"https:\/\/topa.be\/fr\/glossary\/actes-des-apotres\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/topa.be\/fr\/author\/topa\/#author","url":"https:\/\/topa.be\/fr\/author\/topa\/","name":"Marc Dehaese","image":{"@type":"ImageObject","@id":"https:\/\/topa.be\/fr\/glossary\/actes-des-apotres\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/ce0c55c105036574ca271bbee95fc95bcec1e19cb865a85257048c44ee054cb9?s=96&d=mm&r=g","width":96,"height":96,"caption":"Marc Dehaese"}},{"@type":"WebPage","@id":"https:\/\/topa.be\/fr\/glossary\/actes-des-apotres\/#webpage","url":"https:\/\/topa.be\/fr\/glossary\/actes-des-apotres\/","name":"Actes des Ap\u00f4tres | TOPA","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/topa.be\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/topa.be\/fr\/glossary\/actes-des-apotres\/#breadcrumblist"},"author":{"@id":"https:\/\/topa.be\/fr\/author\/topa\/#author"},"creator":{"@id":"https:\/\/topa.be\/fr\/author\/topa\/#author"},"datePublished":"2021-09-27T11:40:57+02:00","dateModified":"2021-09-27T11:40:57+02:00"},{"@type":"WebSite","@id":"https:\/\/topa.be\/fr\/#website","url":"https:\/\/topa.be\/fr\/","name":"TOPA","description":"Antwerpen, Kerken en ToerismeToerismepastoraal, Bisdom Antwerpen (TOPA vzw)","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/topa.be\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"TOPA | Antwerpen, Kerken en ToerismeToerismepastoraal, Bisdom Antwerpen (TOPA vzw)","og:type":"article","og:title":"Actes des Ap\u00f4tres | TOPA","og:url":"https:\/\/topa.be\/fr\/glossary\/actes-des-apotres\/","article:published_time":"2021-09-27T09:40:57+00:00","article:modified_time":"2021-09-27T09:40:57+00:00","twitter:card":"summary","twitter:title":"Actes des Ap\u00f4tres | TOPA"},"aioseo_meta_data":{"post_id":"57500","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":{"id":"aioseo-web-page-6392b3fc51003","slug":"web-page","graphName":"WebPage","label":"Webpagina","properties":{"type":"WebPage","name":"","description":""}}},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":{"locations":{"business":{"name":"","businessType":"","image":"","areaServed":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"streetLine1":"","streetLine2":"","zipCode":"","city":"","state":"","country":"","addressFormat":"#streetLineOne\n#streetLineTwo\n#city, #state #zipCode"},"contact":{"email":"","phone":"","phoneFormatted":"","fax":"","faxFormatted":""},"ids":{"vat":"","tax":"","chamberOfCommerce":""},"payment":{"priceRange":"","currenciesAccepted":"","methods":""}}},"openingHours":{"useDefaults":true,"show":true,"alwaysOpen":false,"use24hFormat":false,"timezone":"","labels":{"closed":"","alwaysOpen":""},"days":{"monday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"tuesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"wednesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"thursday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"friday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"saturday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"sunday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"}}}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-09-27 09:40:57","updated":"2025-06-11 14:47:32","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/topa.be\/fr\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/topa.be\/fr\/glossary\/\" title=\"Glossary Terms\">Glossary Terms<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/topa.be\/fr\/glossary-cat\/la-foi\/\" title=\"La foi\">La foi<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tActes des Ap\u00f4tres\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/topa.be\/fr\/"},{"label":"Glossary Terms","link":"https:\/\/topa.be\/fr\/glossary\/"},{"label":"La foi","link":"https:\/\/topa.be\/fr\/glossary-cat\/la-foi\/"},{"label":"Actes des Ap\u00f4tres","link":"https:\/\/topa.be\/fr\/glossary\/actes-des-apotres\/"}],"related_terms":"","external_url":"","internal_reference_id":"","_links":{"self":[{"href":"https:\/\/topa.be\/fr\/wp-json\/wp\/v2\/glossary\/57500","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/topa.be\/fr\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/topa.be\/fr\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/topa.be\/fr\/wp-json\/wp\/v2\/users\/16"}],"version-history":[{"count":0,"href":"https:\/\/topa.be\/fr\/wp-json\/wp\/v2\/glossary\/57500\/revisions"}],"wp:attachment":[{"href":"https:\/\/topa.be\/fr\/wp-json\/wp\/v2\/media?parent=57500"}],"wp:term":[{"taxonomy":"glossary-cat","embeddable":true,"href":"https:\/\/topa.be\/fr\/wp-json\/wp\/v2\/glossary-cat?post=57500"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}